{"id":238,"date":"2022-10-18T20:04:14","date_gmt":"2022-10-18T20:04:14","guid":{"rendered":"https:\/\/singerlatam.com\/argentina\/?page_id=238"},"modified":"2022-10-18T20:04:14","modified_gmt":"2022-10-18T20:04:14","slug":"historia","status":"publish","type":"page","link":"https:\/\/singerlatam.com\/argentina\/historia\/","title":{"rendered":"Historia"},"content":{"rendered":"<h2><strong>Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850.<\/strong><\/h2>\n<p>Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida la primera m\u00e1quina de zig-zag del mundo, las primeras m\u00e1quinas electr\u00f3nicas y ahora producimos con orgullo las m\u00e1quinas de coser y bordar para el hogar m\u00e1s avanzadas del mundo. Desde la decoraci\u00f3n del hogar y la confecci\u00f3n de ropa hasta el bordado y el acolchado, SINGER\u00ae se dedica a ayudar a las personas a expresarse a trav\u00e9s del arte de la costura.<\/p>\n<h2><strong>\u00a1Hoy SINGER est\u00e1 festejando el 170\u00b0 Aniversario de la patente de la primera m\u00e1quina de coser dom\u00e9stica!<\/strong><\/h2>\n<p>Este aniversario marc\u00f3 el inicio oficial de SINGER\u00ae como empresa y su liderazgo en la industria desde el principio, un gran logro. Nuestro liderazgo en la industria se ha mantenido hasta el d\u00eda de hoy gracias a nuestro compromiso continuo con la calidad, confiabilidad, innovaci\u00f3n y servicio.<\/p>\n<h2>Cronolog\u00eda<\/h2>\n<p><strong>1850<\/strong>: Isaac Merritt Singer inventa la primera m\u00e1quina de coser pr\u00e1ctica del mundo.<\/p>\n<p><strong>1851:<\/strong>\u00a0Patente emitida para la primera m\u00e1quina de coser de la marca SINGER el 12 de agosto de 1851.<\/p>\n<p><strong>1855<\/strong>: La marca SINGER recibe el primer premio en la Feria Mundial de Par\u00eds, Francia. Ese mismo a\u00f1o, SINGER se convierte en la marca de m\u00e1quinas de coser m\u00e1s vendida a nivel internacional.<\/p>\n<p><strong>1858<\/strong>: La marca SINGER presenta la primera m\u00e1quina dom\u00e9stica ligera, Grasshopper\u2122.<\/p>\n<p><strong>1865<\/strong>: La marca SINGER ofrece la m\u00e1quina de coser \u00abNew Family\u00bb. Finaliza la Guerra Civil de EE. UU.<\/p>\n<p><strong>1870<\/strong>: La marca de ni\u00f1a SINGER Brand Red \u201cS\u201d hace su debut. Su marca comercial se produce en varios idiomas, convirti\u00e9ndose en una de las marcas comerciales m\u00e1s reconocidas del mundo.<\/p>\n<p><strong>1889<\/strong>: La marca SINGER presenta la primera m\u00e1quina de coser electr\u00f3nica pr\u00e1ctica<\/p>\n<p><strong>1890<\/strong>: La marca SINGER alcanza el 90% de cuota de mercado a nivel mundial.<\/p>\n<p><strong>1921<\/strong>: La marca SINGER presenta la m\u00e1quina Portable Electric\u2122, una modelo motorizado.<\/p>\n<p><strong>1929<\/strong>:\u00a0Las ventas estadounidenses generales de m\u00e1quinas de coser caen. La marca SINGER atribuye esto a la tendencia social Flapper, que presenta a mujeres emancipadas que se estaban alejando del papel tradicional de ama de casa.<\/p>\n<p><strong>1933<\/strong>: La m\u00e1quina de coser Featherweight\u2122 221 se presenta en la Feria Mundial de Chicago. Esta m\u00e1quina permanece en producci\u00f3n durante m\u00e1s de 30 a\u00f1os y sigue siendo una imagen ic\u00f3nica de la marca SINGER.<\/p>\n<p><strong>1939-1945<\/strong>: La marca SINGER deja de desarrollar m\u00e1quinas de coser para centrarse en la producci\u00f3n de art\u00edculos de guerra.<\/p>\n<p><strong>1951<\/strong>: Los 600 centros de costura de la marca SINGER han capacitado a unas 400.000 amas de casa.<\/p>\n<p><strong>1952<\/strong>: La marca SINGER presenta su Slant-o-Matic\u2122, la primera m\u00e1quina de zigzag.<\/p>\n<p><strong>1975<\/strong>:\u00a0La marca SINGER presenta la primera m\u00e1quina de coser electr\u00f3nica del mundo, la Athena 2000.<\/p>\n<p><strong>1978<\/strong>: La marca SINGER presenta la m\u00e1quina Touchtronic\u2122 2001, la primera m\u00e1quina del mundo controlada por computadora.<\/p>\n<p><strong>1985<\/strong>: La marca SINGER presenta una l\u00ednea completamente nueva de m\u00e1quinas de coser de \u00faltima generaci\u00f3n con modelos dise\u00f1ados para satisfacer las necesidades y presupuestos individuales, que incluyen innovaciones para patrones de puntadas, monogramas y bordados.<\/p>\n<p><strong>2001<\/strong>: La marca SINGER celebra su 150 aniversario. Lanza la m\u00e1quina de coser y bordar para el hogar m\u00e1s avanzada del mundo: la m\u00e1quina Quantum XL-5000, con uno de los sistemas m\u00e1s potentes y f\u00e1ciles de usar del mercado.<\/p>\n<p><strong>2005<\/strong>:\u00a0La marca SINGER presenta la m\u00e1quina Futura\u2122, la m\u00e1quina de bordar habilitada por computadora m\u00e1s asequible\u00a0en el mercado.<\/p>\n<p><strong>2007<\/strong>:\u00a0Presenta la m\u00e1quina Inspiration, una nueva e ic\u00f3nica m\u00e1quina de nivel de entrada<br \/>\nutilizando los avances modernos para acentuar la facilidad y la simplicidad.<\/p>\n<p><strong>2010<\/strong>:\u00a0Lanza la segunda generaci\u00f3n de m\u00e1quina de costura y bordado Futura\u00a0XL 400.<\/p>\n<p><strong>2011<\/strong>:\u00a0La marca SINGER celebra su 160 aniversario, marcado por la patente emitida de la primera m\u00e1quina de coser SINGER el 12 de agosto de 1851.<\/p>\n<p><strong>2015<\/strong>: Lanzamiento de la nueva l\u00ednea de m\u00e1quinas con caracter\u00edsticas modernas y el dise\u00f1o ic\u00f3nico de la carrocer\u00eda SINGER.<\/p>\n<p><strong>2017<\/strong>: \u00a1SINGER lanza la primera aplicaci\u00f3n de Asistente de Costura del mundo para ayudar a coser sobre la marcha!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-238","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/singerlatam.com\/argentina\/historia\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\n\t\t<style>.page-id-270 div#main-slider {\n display: none;\n}<\/style>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SINGER\u00ae Argentina - M\u00e1quinas de coser y bordar\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Historia - SINGER\u00ae Argentina\" \/>\n\t\t<meta property=\"og:description\" content=\"Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/singerlatam.com\/argentina\/historia\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/singerlatam.com\/argentina\/wp-content\/uploads\/sites\/2\/2026\/02\/logo-singer.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/singerlatam.com\/argentina\/wp-content\/uploads\/sites\/2\/2026\/02\/logo-singer.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-10-18T20:04:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-10-18T20:04:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Historia - SINGER\u00ae Argentina\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/singerlatam.com\/argentina\/wp-content\/uploads\/sites\/2\/2026\/02\/logo-singer.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/singerlatam.com\\\/argentina\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/#listItem\",\"name\":\"Historia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/#listItem\",\"position\":2,\"name\":\"Historia\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/#organization\",\"name\":\"Singer Argentina\",\"description\":\"M\\u00e1quinas de coser y bordar\",\"url\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/logo-singer.svg\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/#organizationLogo\",\"caption\":\"SINGER\\u00ae - 175 a\\u00f1os\"},\"image\":{\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/#webpage\",\"url\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/\",\"name\":\"Historia - SINGER\\u00ae Argentina\",\"description\":\"Isaac Merrit Singer invent\\u00f3 la primera m\\u00e1quina de coser dom\\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\\u00f3nimo de costura. El esp\\u00edritu de dise\\u00f1o pr\\u00e1ctico e innovaci\\u00f3n creativa que caracteriz\\u00f3 a la empresa en sus inicios contin\\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/historia\\\/#breadcrumblist\"},\"datePublished\":\"2022-10-18T20:04:14-05:00\",\"dateModified\":\"2022-10-18T20:04:14-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/#website\",\"url\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/\",\"name\":\"Singer Argentina\",\"description\":\"M\\u00e1quinas de coser y bordar\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/singerlatam.com\\\/argentina\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Historia - SINGER\u00ae Argentina","description":"Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida","canonical_url":"https:\/\/singerlatam.com\/argentina\/historia\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;style&gt;.page-id-270 div#main-slider {\n display: none;\n}&lt;\/style&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/singerlatam.com\/argentina\/historia\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/singerlatam.com\/argentina#listItem","position":1,"name":"Inicio","item":"https:\/\/singerlatam.com\/argentina","nextItem":{"@type":"ListItem","@id":"https:\/\/singerlatam.com\/argentina\/historia\/#listItem","name":"Historia"}},{"@type":"ListItem","@id":"https:\/\/singerlatam.com\/argentina\/historia\/#listItem","position":2,"name":"Historia","previousItem":{"@type":"ListItem","@id":"https:\/\/singerlatam.com\/argentina#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/singerlatam.com\/argentina\/#organization","name":"Singer Argentina","description":"M\u00e1quinas de coser y bordar","url":"https:\/\/singerlatam.com\/argentina\/","logo":{"@type":"ImageObject","url":"https:\/\/singerlatam.com\/argentina\/wp-content\/uploads\/sites\/2\/2026\/02\/logo-singer.svg","@id":"https:\/\/singerlatam.com\/argentina\/historia\/#organizationLogo","caption":"SINGER\u00ae - 175 a\u00f1os"},"image":{"@id":"https:\/\/singerlatam.com\/argentina\/historia\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/singerlatam.com\/argentina\/historia\/#webpage","url":"https:\/\/singerlatam.com\/argentina\/historia\/","name":"Historia - SINGER\u00ae Argentina","description":"Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/singerlatam.com\/argentina\/#website"},"breadcrumb":{"@id":"https:\/\/singerlatam.com\/argentina\/historia\/#breadcrumblist"},"datePublished":"2022-10-18T20:04:14-05:00","dateModified":"2022-10-18T20:04:14-05:00"},{"@type":"WebSite","@id":"https:\/\/singerlatam.com\/argentina\/#website","url":"https:\/\/singerlatam.com\/argentina\/","name":"Singer Argentina","description":"M\u00e1quinas de coser y bordar","inLanguage":"es-ES","publisher":{"@id":"https:\/\/singerlatam.com\/argentina\/#organization"}}]},"og:locale":"es_ES","og:site_name":"SINGER\u00ae Argentina - M\u00e1quinas de coser y bordar","og:type":"article","og:title":"Historia - SINGER\u00ae Argentina","og:description":"Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida","og:url":"https:\/\/singerlatam.com\/argentina\/historia\/","og:image":"https:\/\/singerlatam.com\/argentina\/wp-content\/uploads\/sites\/2\/2026\/02\/logo-singer.svg","og:image:secure_url":"https:\/\/singerlatam.com\/argentina\/wp-content\/uploads\/sites\/2\/2026\/02\/logo-singer.svg","article:published_time":"2022-10-18T20:04:14+00:00","article:modified_time":"2022-10-18T20:04:14+00:00","twitter:card":"summary_large_image","twitter:title":"Historia - SINGER\u00ae Argentina","twitter:description":"Isaac Merrit Singer invent\u00f3 la primera m\u00e1quina de coser dom\u00e9stica en 1850. Desde 1851, el nombre Singer es sin\u00f3nimo de costura. El esp\u00edritu de dise\u00f1o pr\u00e1ctico e innovaci\u00f3n creativa que caracteriz\u00f3 a la empresa en sus inicios contin\u00faa hoy a medida que desarrollamos productos para todos los niveles de costura. Hemos celebrado muchas novedades, incluida","twitter:image":"https:\/\/singerlatam.com\/argentina\/wp-content\/uploads\/sites\/2\/2026\/02\/logo-singer.svg"},"aioseo_meta_data":{"post_id":"238","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-10-18 20:04:14","updated":"2025-07-09 19:12:08","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/singerlatam.com\/argentina\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHistoria\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/singerlatam.com\/argentina"},{"label":"Historia","link":"https:\/\/singerlatam.com\/argentina\/historia\/"}],"_links":{"self":[{"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/pages\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/comments?post=238"}],"version-history":[{"count":1,"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/pages\/238\/revisions"}],"predecessor-version":[{"id":239,"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/pages\/238\/revisions\/239"}],"wp:attachment":[{"href":"https:\/\/singerlatam.com\/argentina\/wp-json\/wp\/v2\/media?parent=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}